{"id":246651,"date":"2022-08-18T16:20:44","date_gmt":"2022-08-18T14:20:44","guid":{"rendered":"https:\/\/sherpas.com\/blog\/?p=246651"},"modified":"2025-01-07T10:43:57","modified_gmt":"2025-01-07T09:43:57","slug":"developpeur-informatique","status":"publish","type":"post","link":"https:\/\/sherpas.com\/blog\/developpeur-informatique\/","title":{"rendered":"D\u00e9couvre le m\u00e9tier de d\u00e9veloppeur informatique ! \ud83d\udcbb"},"content":{"rendered":"\n<p>Le <strong>m\u00e9tier de d\u00e9veloppeur informatique<\/strong> ne cesse de cro\u00eetre <strong>\u00e0 l\u2019heure du 100% num\u00e9rique<\/strong>. Si tu ma\u00eetrises l\u2019informatique sur le bout des doigts et que tu te sens \u00e0 l\u2019aise avec le code, ce m\u00e9tier est peut-\u00eatre fait pour toi ! Formation, salaire, avantages et inconv\u00e9nients,<strong> toutes les informations dont tu as besoin <\/strong>sont ici. \ud83d\udc47<\/p>\n\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p>\u2705 Notre <a href=\"https:\/\/sherpas.com\/blog\/entretien-avec-un-developpeur\/\" target=\"_blank\" rel=\"noopener\">entretien avec Jean, d\u00e9veloppeur chez Les Sherpas<\/a> !<\/p>\n\n        <\/div>\n    <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cest-quoi-le-metier-de-developpeur-informatique\">C\u2019est quoi le m\u00e9tier de d\u00e9veloppeur informatique ? \ud83e\udd14<\/h2>\n\n\n\n<p>Le d\u00e9veloppeur informatique, c\u2019est un v\u00e9ritable <strong>sp\u00e9cialiste de la programmation<\/strong>, un <strong>expert des langages informatiques<\/strong>, celui qu\u2019on appelle pour mettre au point un logiciel, un site web, une application\u2026&nbsp;<\/p>\n\n\n<section class=\"you-know\">\n                <div class=\"you-know__title\"><p>\ud83d\udca1 Le savais-tu ?<\/p>\n<\/div>\n                        <div class=\"you-know__text\">\n            <p>Il existe <strong>plusieurs types de d\u00e9veloppeurs<\/strong> qui travaillent diff\u00e9remment. Il y a par exemple ceux qui se concentrent sur le <em>frontend<\/em>,\u00a0 c\u2019est \u00e0 dire <strong>ce que l\u2019utilisateur voit directement<\/strong>, et ceux qui sont sp\u00e9cialis\u00e9s dans le <em>backend<\/em>, ce sont <strong>toutes les choses que l\u2019on ne voit pas mais qui sont indispensables au produit fini<\/strong>. Un programmateur qui ma\u00eetrise les deux est appel\u00e9 un d\u00e9veloppeur <em>fullstack<\/em>, la grande classe quoi ! \ud83d\ude0e<\/p>\n\n        <\/div>\n              <\/section>\n\n\n\n<p>\ud83d\udca1 On pr\u00e9f\u00e8re le dire d\u2019embl\u00e9e : \u00eatre d\u00e9veloppeur informatique, c\u2019est une excellente id\u00e9e de carri\u00e8re professionnelle ! Eh oui, avec <strong>le boom d\u2019Internet et des nouvelles technologies de ces derni\u00e8res ann\u00e9es, le m\u00e9tier est tr\u00e8s en vue parmi les recruteurs<\/strong> et l\u2019on peut maintenant l\u2019exercer \u00e0 peu pr\u00e8s partout\u2026&nbsp;<\/p>\n\n\n\n<p>Tu doutes de ce qu\u2019on affirme ? D\u2019accord, alors voyons ensemble <strong>tous les domaines o\u00f9 un d\u00e9veloppeur informatique peut s\u2019av\u00e9rer utile<\/strong>. \ud83d\udc47<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les <strong>grandes entreprises<\/strong> (banques, assurances, commerce en ligne\u2026)<\/li>\n\n\n\n<li>Le milieu du <strong>jeu vid\u00e9o<\/strong><\/li>\n\n\n\n<li>Les groupes de <strong>m\u00e9dias<\/strong><\/li>\n\n\n\n<li>La <strong>fonction publique<\/strong><\/li>\n<\/ul>\n\n\n\n<p>\ud83d\udc49 La liste est non exhaustive puisqu\u2019il te suffit d\u2019imaginer <strong>n\u2019importe quel domaine d\u2019activit\u00e9 en rapport avec le monde num\u00e9rique<\/strong> pour te rendre compte du nombre de possibilit\u00e9s qu\u2019un d\u00e9veloppeur informatique peut avoir en termes de carri\u00e8re.<\/p>\n\n\n<section class=\"you-know\">\n                <div class=\"you-know__title\"><p>\ud83d\udca1 Le savais-tu ?<\/p>\n<\/div>\n                        <div class=\"you-know__text\">\n            <p>Depuis quelques ann\u00e9es, le m\u00e9tier de d\u00e9veloppeur informatique est <a href=\"https:\/\/www.lemonde.fr\/campus\/article\/2022\/04\/03\/rock-stars-du-marche-de-l-emploi-les-developpeurs-web-craignent-de-devenir-les-ouvriers-d-hier_6120349_4401467.html\" target=\"_blank\" rel=\"nofollow noopener\">l\u2019un des plus recherch\u00e9 et convoit\u00e9 par les recruteurs<\/a>, aussi bien en France qu\u2019\u00e0 l\u2019\u00e9tranger. Le moins que l\u2019on puisse dire, c\u2019est que <strong>dans ce secteur le march\u00e9 de l\u2019emploi est tr\u00e8s dynamique<\/strong> !<\/p>\n\n        <\/div>\n              <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"comment-devenir-developpeur-informatique\">Comment devenir d\u00e9veloppeur informatique ? \ud83c\udf93<\/h2>\n\n\n\n<p>Pour pr\u00e9tendre \u00e0 un poste de d\u00e9veloppeur informatique, <strong>plusieurs formations sont possibles et le niveau de recrutement est tr\u00e8s variable<\/strong>. Selon le poste vis\u00e9 et les comp\u00e9tences n\u00e9cessaires, le m\u00e9tier peut <strong>aussi bien \u00eatre accessible apr\u00e8s de courtes \u00e9tudes qu\u2019apr\u00e8s des cursus plus longs<\/strong>.<\/p>\n\n\n<section class=\"you-know\">\n                <div class=\"you-know__title\"><p>\ud83d\udccc Le conseil des Sherpas<\/p>\n<\/div>\n                        <div class=\"you-know__text\">\n            <p>Si tu en as l\u2019occasion, renseigne-toi sur la possibilit\u00e9 de faire ta <a href=\"https:\/\/sherpas.com\/blog\/pourquoi-choisir-lalternance\/\" target=\"_blank\" rel=\"noopener\"><strong>formation en alternance<\/strong><\/a>. Rien de tel qu\u2019une <strong>immersion dans le monde de l\u2019entreprise<\/strong> pour mettre en usage ce que l\u2019on apprend en cours !<\/p>\n\n        <\/div>\n              <\/section>\n\n\n\n<p>On te propose donc un <strong>aper\u00e7u g\u00e9n\u00e9ral des diff\u00e9rentes formations<\/strong> qui permettent de s\u2019ins\u00e9rer sur le march\u00e9 de l\u2019emploi des d\u00e9veloppeurs informatiques et programmeurs. \ud83d\udc47<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/sherpas.com\/content\/uploads\/2023\/10\/elmo-pass-out-min.gif\" alt=\"Trop de choix ! \" class=\"wp-image-265990\" style=\"width:500px;height:282px\" width=\"500\" height=\"282\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"bac-2\">Bac +2<\/h3>\n\n\n\n<p>Une formation <strong>rapide mais efficace<\/strong>, qui permet de te lancer rapidement dans le monde professionnel et de ne pas passer trop de temps sur les bancs de l\u2019\u00e9cole !<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le <strong>BTS SIO (Services Informatiques aux Organisations)<\/strong> et ses deux parcours : <strong>SISR (Solutions d\u2019Infrastructure, Syst\u00e8mes et R\u00e9seaux)<\/strong> plut\u00f4t centr\u00e9 sur la conception et la maintenance d&rsquo;infrastructures r\u00e9seaux et <strong>SLAM (Solutions Logicielles et Applications M\u00e9tiers)<\/strong> pour ceux qui veulent se sp\u00e9cialiser dans le d\u00e9veloppement num\u00e9rique.<\/li>\n<\/ul>\n\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p>\u2705 D\u00e9couvre en d\u00e9tail le <a href=\"https:\/\/sherpas.com\/blog\/programme-bts-sio\/\" target=\"_blank\" rel=\"noopener\">programme du BTS SIO<\/a> !<\/p>\n\n        <\/div>\n    <\/section>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le <strong>BTS SN (Syst\u00e8mes Num\u00e9riques)<\/strong> et ses deux parcours : <strong>IR (Informatique et R\u00e9seaux)<\/strong> qui s\u2019int\u00e9resse aux r\u00e9seaux et \u00e0 leur s\u00e9curit\u00e9 et <strong>EC (\u00c9lectronique et communication)<\/strong> centr\u00e9 sur la mise en \u0153uvre du produit.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"bac-3\">Bac +3<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le <strong>BUT Informatique<\/strong>, ex-DUT Informatique<\/li>\n<\/ul>\n\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p>\u2705 Mais au fait, <a href=\"https:\/\/sherpas.com\/blog\/qu-est-ce-qu-un-but\/\" target=\"_blank\" rel=\"noopener\">c\u2019est quoi un BUT ?<\/a><\/p>\n\n        <\/div>\n    <\/section>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La <strong>licence professionnelle mention M\u00e9tiers de l&rsquo;Informatique<\/strong> ou <strong>la licence professionnelle M\u00e9tiers des R\u00e9seaux et T\u00e9l\u00e9communications<\/strong> et leurs diff\u00e9rents parcours qui varient en fonction de l\u2019universit\u00e9 o\u00f9 tu \u00e9tudies !<\/li>\n\n\n\n<li>Le <strong>Bachelor Informatique<\/strong>, issu d\u2019\u00e9coles sp\u00e9cialis\u00e9es et priv\u00e9es !<\/li>\n<\/ul>\n\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p>\u2705 Tout savoir sur <a href=\"https:\/\/sherpas.com\/blog\/qu-est-ce-qu-un-bachelor\/\" target=\"_blank\" rel=\"noopener\">le bachelor<\/a> !<\/p>\n\n        <\/div>\n    <\/section>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"bac-4-bac-5-plus\">Bac +4, Bac +5 &amp; plus\u2026<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les <strong>dipl\u00f4mes d&rsquo;\u00e9coles sp\u00e9cialis\u00e9es en informatique<\/strong> : <a href=\"https:\/\/sherpas.com\/blog\/trouver-ta-voie\/orientation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Epitech<\/a>, <a href=\"https:\/\/sherpas.com\/blog\/trouver-ta-voie\/orientation\/\" target=\"_blank\" rel=\"noreferrer noopener\">SupInfo<\/a>\u2026<\/li>\n<\/ul>\n\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p>\u2705 Toutes les infos sur les <a href=\"https:\/\/sherpas.com\/blog\/ecole-d-ingenieur-informatique\/\" target=\"_blank\" rel=\"noopener\">\u00e9coles d\u2019ing\u00e9nieurs sp\u00e9cialis\u00e9es<\/a><\/p>\n\n        <\/div>\n    <\/section>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le <strong>Master pro DAPM<\/strong> (D\u00e9veloppement et Applications sur Plateformes Mobiles) de Toulon<\/li>\n\n\n\n<li>Le <strong>Master pro D\u00e9veloppement logiciel<\/strong> de Toulouse<\/li>\n<\/ul>\n\n\n\n<p>On pr\u00e9cise que la liste est non exhaustive, <strong>les formations en informatique fleurissent sur tout le territoire<\/strong>. Si c\u2019est un domaine qui t\u2019int\u00e9resse, tu trouveras forc\u00e9ment chaussure \u00e0 ton pied !<\/p>\n\n\n<section class=\"push \">\n        <div >\n            \n                                                <div class=\"push__container  qcd\" data-target=\"_self\" data-qcd=\"aHR0cHM6Ly9zaGVycGFzLmNvbS9mdW5uZWwtc3R1ZGVudC1xdWFsaWZpY2F0aW9u\" data-banner=\"2\" data-name=\"Cours part&amp;rsquo; global #2 = CPG2\" style=\"background-color: #F3FBF7\" >\n                                                                        <div class=\"push__teachers\">\n    <div class=\"d-flex justify-content-center d-md-none\">\n        <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\" alt=\"Logo Sherpas\">\n    <\/div>\n    <div class=\"swiper\">\n        <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Cle\u0301mence2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Cl\u00e9mence<\/p>                          <p class=\"push__teachers-school\">HEC Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">21\u20ac\/h\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Thibault2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Thibault<\/p>                          <p class=\"push__teachers-school\">ENS Paris Ulm<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">20\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Sophie2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Sophie<\/p>                          <p class=\"push__teachers-school\">Sciences Po Bordeaux<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">12\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Noemie2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">No\u00e9mie<\/p>                          <p class=\"push__teachers-school\">M2 en droit \u00e0 Assas<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Fanny2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Fanny<\/p>                          <p class=\"push__teachers-school\">Ponts ParisTech<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Simon2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Simon<\/p>                          <p class=\"push__teachers-school\">4e ann\u00e9e de m\u00e9decine<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">26\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Nicolas2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Nicolas<\/p>                          <p class=\"push__teachers-school\">CentraleSup\u00e9lec<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">17\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Victor2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Victor<\/p>                          <p class=\"push__teachers-school\">ESCP<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">25\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                                                    <div class=\"push__content\">\n                                                            <div  class=\"d-none d-md-block\" >\n                                    <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\"\n                                        alt=\"Logo Sherpas\">\n                                <\/div>\n                                                                                        <div class=\"push__title\"><p>Besoin d&rsquo;un prof particulier ? <span role=\"img\" aria-label=\"\u2728\">\u2728<\/span><!-- notionvc: 9b5ed38b-ea2e-4d3c-a3bb-f0091c2eedd2 --><\/p>\n<\/div>\n                                                                                        <div class=\"push__text\"><p>Nos profs sont l\u00e0 pour t&rsquo;aider \u00e0 progresser !<\/p>\n<p>&nbsp;<\/p>\n<p><!-- notionvc: 20490bdd-6579-484b-9d99-0ff0bc1aa8e7 --><\/p>\n<\/div>\n                                                        <div class=\"push__promo-button   \">\n                                                                                                    <div\n                                        class=\"btn btn-primary\"\n                                        style=\"color: ; border-color: ; background-color: \"\n\n                                    >\n                                        JE PRENDS UN COURS OFFERT !\n                                    <\/div>\n                                                            <\/div>\n                                                    <\/div>\n                                    <\/div>\n                                    <\/div>\n    <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"les-missions-du-developpeur-informatique\">Les missions du d\u00e9veloppeur informatique \u2705<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"analyser\">Analyser \ud83e\uddd0<\/h3>\n\n\n\n<p>Avant toute chose, la mission du d\u00e9veloppeur informatique est d\u2019<strong>analyser le produit sur lequel il travaille<\/strong>, afin de commencer le c\u0153ur de sa mission sur de bonnes bases. Pour cela, il doit par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Identifier les <strong>besoins et attentes des utilisateurs<\/strong><\/li>\n\n\n\n<li>Mais aussi les <strong>besoins et attentes de son employeur <\/strong>ou client !<\/li>\n\n\n\n<li>R\u00e9fl\u00e9chir aux <strong>techniques qu\u2019il peut mettre en place<\/strong><\/li>\n\n\n\n<li>Veiller \u00e0 respecter le <strong>cahier des charges<\/strong> initial<\/li>\n<\/ul>\n\n\n\n<p>Il ne s\u2019agit que d\u2019une \u00e9tape pr\u00e9alable et ne repr\u00e9sente qu\u2019une <strong>infime partie du v\u00e9ritable travail du d\u00e9veloppeur informatique<\/strong>. Elle reste toutefois primordiale et essentielle, il ne faut donc pas la n\u00e9gliger ! \ud83d\ude2c<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/sherpas.com\/content\/uploads\/2023\/10\/alderiate-crane-min.gif\" alt=\"Quand tu as beaucoup trop de donn\u00e9es \u00e0 analyser\u2026\" class=\"wp-image-265992\" style=\"width:503px;height:283px\" width=\"503\" height=\"283\" \/><figcaption class=\"wp-element-caption\"><em>Quand tu as beaucoup trop de donn\u00e9es \u00e0 analyser\u2026<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"programmer\">Programmer \u2328\ufe0f<\/h3>\n\n\n\n<p>C\u2019est \u00e0 partir de l\u00e0 que l\u2019on rentre dans le vif du sujet et que <strong>le codage pur et dur commence<\/strong>. La v\u00e9ritable programmation se fait en plusieurs \u00e9tapes : il est d\u2019usage de <strong>proposer une version B\u00eata<\/strong> du produit avant toute chose.<\/p>\n\n\n\n<p>\ud83d\udc49 La version B\u00eata, c\u2019est une sorte de <strong>prototype qui permet de pr\u00e9visualiser le rendu final<\/strong> du produit, mais aussi de rep\u00e9rer les \u00e9ventuels bugs et dysfonctionnements.<\/p>\n\n\n\n<p>La mission du d\u00e9veloppeur informatique est ensuite d\u2019avancer progressivement vers la version finale du produit. Pour cela, il faut <strong>coder et programmer en fonction des observations soulev\u00e9es par la version B\u00eata<\/strong> ainsi que mettre en place un lancement efficace, qui se d\u00e9roule sans probl\u00e8me !<\/p>\n\n\n\n<p>Tout cela est valable aussi bien pour des <strong>sites web, des applications, des logiciels, des jeux vid\u00e9o<\/strong>\u2026 Bref, tout ce qui est possible et imaginable pour un d\u00e9veloppeur informatique et un programmeur !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"assurer-la-maintenance\">Assurer la maintenance \u2699\ufe0f<\/h3>\n\n\n\n<p>Une fois que le lancement de la version finale du produit est pass\u00e9, le travail du d\u00e9veloppeur informatique est\u2026 <strong>Absolument pas termin\u00e9<\/strong> !&nbsp;<\/p>\n\n\n\n<p>\ud83d\udc49 <strong>Tout produit num\u00e9rique est am\u00e9liorable<\/strong> ou r\u00e9parable en quelques clics, avec l\u2019aide de quelques lignes de code\u2026<\/p>\n\n\n\n<p>La mission du d\u00e9veloppeur informatique est donc de veiller au bon fonctionnement du fruit de son travail et de <strong>r\u00e9gler les \u00e9ventuels probl\u00e8mes<\/strong> d\u00e9cel\u00e9s en mettant au point des mises \u00e0 jour, des correctifs\u2026<\/p>\n\n\n\n<p>Durant cette phase, le d\u00e9veloppeur informatique peut aussi \u00eatre amen\u00e9 \u00e0 <strong>mettre en place un support d\u2019aide technique ou \u00e0 organiser des formations<\/strong> pour les outils sur lesquels il a travaill\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"participer-a-levolution-de-la-plateforme\">Participer \u00e0 l\u2019\u00e9volution de la plateforme \ud83d\udcca<\/h3>\n\n\n\n<p>Le d\u00e9veloppeur informatique est aussi amen\u00e9 \u00e0 <strong>adapter ou am\u00e9liorer les programmes<\/strong> dont il est le cr\u00e9ateur. Cela peut par exemple se faire lors du <strong>lancement d\u2019un nouveau projet au sein de l\u2019entreprise <\/strong>o\u00f9 il exerce.&nbsp;<\/p>\n\n\n\n<p>\ud83d\udd01 Il doit alors <strong>reprendre les \u00e9tapes abord\u00e9es pr\u00e9c\u00e9demment<\/strong> : commencer par analyser les besoins de l\u2019utilisateur ou de son client puis programmer progressivement le projet jusqu\u2019au lancement.<\/p>\n\n\n\n<p>Apr\u00e8s cela, le d\u00e9veloppeur informatique sera toujours charg\u00e9 de veiller au bon fonctionnement de son produit. Il doit donc <strong>rester ouvert aux sollicitations et recommandations<\/strong> qui peuvent mener \u00e0 de nouvelles am\u00e9liorations.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/sherpas.com\/content\/uploads\/2023\/10\/something-needs-to-change-dave-olson-min.gif\" alt=\"\u00catre dev\u2019, c\u2019est un \u00e9ternel recommencement !\" class=\"wp-image-265993\" style=\"width:559px;height:296px\" width=\"559\" height=\"296\" \/><figcaption class=\"wp-element-caption\"><em>\u00catre dev\u2019, c\u2019est un \u00e9ternel recommencement !<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"le-salaire-dun-developpeur-informatique\">Le salaire d\u2019un d\u00e9veloppeur informatique \ud83d\udcb8<\/h2>\n\n\n\n<p>D\u2019apr\u00e8s une <a href=\"https:\/\/www.hays.fr\/documents\/63274\/0\/EDRN_2020.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u00e9tude de r\u00e9mun\u00e9ration<\/a>, le salaire d\u2019un d\u00e9veloppeur informatique d\u00e9butant oscille <strong>entre 2600\u20ac et 3100\u20ac bruts par mois<\/strong>.<\/p>\n\n\n\n<p>Cet \u00e9cart s\u2019explique par la <strong>diversit\u00e9 des entreprises<\/strong> qui emploient de d\u00e9veloppeurs mais aussi par la <strong>vari\u00e9t\u00e9 des profils<\/strong> des professionnels de la programmation.<\/p>\n\n\n\n<p>\ud83d\udc49 Les <strong>comp\u00e9tences du d\u00e9veloppeur informatique sont prises en compte<\/strong> pour \u00e9valuer sa r\u00e9mun\u00e9ration : la ma\u00eetrise de certains langages de programmation est particuli\u00e8rement valoris\u00e9e et permet de <strong>se d\u00e9marquer sur le march\u00e9 de l\u2019emploi <\/strong>ainsi que d\u2019obtenir <strong>un salaire avantageux<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"qualites-et-competences-necessaires-pour-devenir-developpeur-informatique\">Qualit\u00e9s et comp\u00e9tences n\u00e9cessaires pour devenir d\u00e9veloppeur informatique \ud83c\udfaf<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"des-competences-a-acquerir\">Des comp\u00e9tences \u00e0 acqu\u00e9rir \ud83d\udcaa<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conna\u00eetre les <strong>techniques de programmation<\/strong><\/li>\n\n\n\n<li>Ma\u00eetriser un ou plusieurs <strong>langages de programmation<\/strong> (JavaScript, C#, Python\u2026)<\/li>\n\n\n\n<li>Avoir une culture g\u00e9n\u00e9rale du num\u00e9rique et <strong>comprendre l\u2019anglais<\/strong><\/li>\n\n\n\n<li>S\u2019adapter aux <strong>contraintes<\/strong> (d\u00e9lais, consignes et budget)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"des-qualites-a-entretenir\">Des qualit\u00e9s \u00e0 entretenir \ud83d\udc4a<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Appr\u00e9cier le <strong>travail d\u2019\u00e9quipe<\/strong> et la coop\u00e9ration<\/li>\n\n\n\n<li>Sens de <strong>l\u2019autonomie<\/strong> lorsque c\u2019est n\u00e9cessaire<\/li>\n\n\n\n<li>Pr\u00e9cision, <strong>rigueur<\/strong> et s\u00e9rieux&nbsp;<\/li>\n\n\n\n<li>Aisance r\u00e9dactionnelle, capacit\u00e9 d\u2019\u00e9coute et d\u2019<strong>adaptation<\/strong><\/li>\n<\/ul>\n\n\n<section class=\"push \">\n        <div >\n            \n                                                <div class=\"push__container  qcd\" data-target=\"_self\" data-qcd=\"aHR0cHM6Ly9zaGVycGFzLmNvbS9mdW5uZWwtc3R1ZGVudC1xdWFsaWZpY2F0aW9u\" data-banner=\"2\" data-name=\"Cours part&amp;rsquo; global #3 = CPG3\" style=\"background-color: #F3FBF7\" >\n                                                                        <div class=\"push__teachers\">\n    <div class=\"d-flex justify-content-center d-md-none\">\n        <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\" alt=\"Logo Sherpas\">\n    <\/div>\n    <div class=\"swiper\">\n        <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Martin2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Martin<\/p>                          <p class=\"push__teachers-school\">HEC Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">23\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Jade2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Jade<\/p>                          <p class=\"push__teachers-school\">Sciences Po Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">21\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Bastien2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Bastien<\/p>                          <p class=\"push__teachers-school\">Polytechnique<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">26\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Emilie2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Emilie<\/p>                          <p class=\"push__teachers-school\">Sciences Po Lyon<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Hugo2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Hugo<\/p>                          <p class=\"push__teachers-school\">Insa Lyon<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">16\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Alma2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Alma<\/p>                          <p class=\"push__teachers-school\">ENS Paris-Saclay<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">24\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/David2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">David<\/p>                          <p class=\"push__teachers-school\">EDHEC<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">25\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Jeanne2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Jeanne<\/p>                          <p class=\"push__teachers-school\">Aix-Marseille Universit\u00e9<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">17\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                                                    <div class=\"push__content\">\n                                                            <div  class=\"d-none d-md-block\" >\n                                    <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\"\n                                        alt=\"Logo Sherpas\">\n                                <\/div>\n                                                                                        <div class=\"push__title\"><p>Besoin de cours particuliers ? <span role=\"img\" aria-label=\"\u2728\">\u2728<\/span><!-- notionvc: 27874cb7-7cca-4c68-a2e3-ea8000cbb55b --><\/p>\n<\/div>\n                                                                                        <div class=\"push__text\"><p><span style=\"color: #48b378;\">4 points<\/span> de plus sur ta <span style=\"color: #48b378;\">moyenne<\/span> avec nos profs Sherpas ! <span role=\"image\" aria-label=\"\ud83d\udcc8\">\ud83d\udcc8<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n                                                        <div class=\"push__promo-button   \">\n                                                                                                    <div\n                                        class=\"btn btn-primary\"\n                                        style=\"color: ; border-color: ; background-color: \"\n\n                                    >\n                                        JE PRENDS UN COURS OFFERT !\n                                    <\/div>\n                                                            <\/div>\n                                                    <\/div>\n                                    <\/div>\n                                    <\/div>\n    <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"avantages-et-inconvenients\">Avantages et inconv\u00e9nients \u2696\ufe0f<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"avantages\">Avantages<\/h3>\n\n\n\n<p>\u2795 Une <strong>forte demande des recruteurs<\/strong> !<\/p>\n\n\n\n<p>\u2795 Un <strong>salaire plut\u00f4t confortable<\/strong><\/p>\n\n\n\n<p>\u2795 La possibilit\u00e9 de <strong>se mettre en freelance<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"inconvenients\">Inconv\u00e9nients<\/h3>\n\n\n\n<p>\u2796 Tu passes <strong>la journ\u00e9e derri\u00e8re un \u00e9cran<\/strong><\/p>\n\n\n\n<p>\u2796 Lourde <strong>charge de travail<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u2796 Tu dois toujours <strong>rester \u00e0 la pointe<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"perspectives-devolution\">Perspectives d\u2019\u00e9volution \ud83d\udcca<\/h2>\n\n\n\n<p>Au cours de sa carri\u00e8re, un d\u00e9veloppeur informatique peut \u00eatre amen\u00e9 \u00e0 <strong>occuper d\u2019autres fonctions<\/strong> au sein de son entreprise ou \u00e0 l\u2019ext\u00e9rieur. Il peut par exemple \u00e9voluer et devenir :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>chef de projet informatique<\/li>\n\n\n\n<li>lead d\u00e9veloppeur (et donc encadrer le travail de programmation)<\/li>\n\n\n\n<li>consultant en codage et programmation<\/li>\n<\/ul>\n\n\n\n<p>Le m\u00e9tier de d\u00e9veloppeur informatique \u00e9tant <strong>particuli\u00e8rement pris\u00e9 dans le monde du travail actuel<\/strong>, il n\u2019est pas compliqu\u00e9 de changer d\u2019entreprise ou de statut. Un d\u00e9veloppeur confirm\u00e9 peut tout \u00e0 fait <strong>se mettre \u00e0 son compte et se lancer en freelance<\/strong>. \ud83d\ude80<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"498\" height=\"280\" src=\"https:\/\/sherpas.com\/content\/uploads\/2023\/10\/we-strictly-freelance-strictly-freelance-min-1.gif\" alt=\"Le freelance signifie la libert\u00e9\" class=\"wp-image-266000\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"les-autres-metiers-du-secteur\">Les autres m\u00e9tiers du secteur \ud83d\udc47<\/h2>\n\n\n\n<p>Le monde du num\u00e9rique est un domaine tr\u00e8s vaste qui risque de <strong>gagner en importance dans l\u2019avenir<\/strong> et propulser de nouveaux m\u00e9tiers sur le devant de la sc\u00e8ne ! Parmi les m\u00e9tiers apparent\u00e9s les plus connus, on retrouve :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>web designer \ud83c\udfa8<\/li>\n\n\n\n<li>data analyste \ud83d\udd0d<\/li>\n\n\n\n<li>juriste sp\u00e9cialis\u00e9 en cybers\u00e9curit\u00e9 \u2696\ufe0f<\/li>\n<\/ul>\n\n\n\n<p>On esp\u00e8re que cette fiche te permettra d\u2019y voir plus clair, <strong>r\u00e9pondra \u00e0 toutes tes questions<\/strong> et que tu connais d\u00e9sormais le m\u00e9tier de d\u00e9veloppeur informatique comme personne ! \ud83d\ude04<\/p>\n\n\n<section class=\"relance\">\n        <div >\n                            <a target=\"_blank\" href=\"https:\/\/sherpas.com\/blog\/guide-orientation\/\">\n                    <div class=\"relance__container\"\n                        >\n                        \n                                                        <picture>\n                            <source srcset=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/valentin-antonucci-450400-unsplash-e1544008908529.jpg\" media=\"(min-width: 999px)\">\n                            <source srcset=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/valentin-antonucci-450400-unsplash-e1544008908529.jpg\" media=\"(max-width: 999px)\">\n                                <img decoding=\"async\"\n                                    src=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/valentin-antonucci-450400-unsplash-e1544008908529.jpg\"\n                                    alt=\"L'orientation\"\n                                >\n                            <\/picture>\n                                                <div class=\"relance__content\">\n                            \n                                <div class=\"relance__title\"> <p>Besoin de plus d&rsquo;infos sur l&rsquo;orientation ? T\u00e9l\u00e9charge notre guide complet, on t&rsquo;explique tout ! \ud83d\ude09<\/p>\n<\/div>\n                                                        <button type=\"button\"\n                                    class=\"relance__button btn btn-white\">\n                                CLIQUE ICI\n                            <\/button>\n                        <\/div>\n                    <\/div>\n                <\/a>\n                    <\/div>\n    <\/section>\n\n    \n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;246651&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;4&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Tu as aim\u00e9 cet article ?&quot;,&quot;legend&quot;:&quot;5\\\/5 - (4 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;D\u00e9couvre le m\u00e9tier de d\u00e9veloppeur informatique ! \ud83d\udcbb&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (4 votes)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le m\u00e9tier de d\u00e9veloppeur informatique ne cesse de cro\u00eetre \u00e0 l\u2019heure du 100% num\u00e9rique. Si tu ma\u00eetrises l\u2019informatique (&#8230;)<\/p>\n","protected":false},"author":326,"featured_media":246660,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"category":[135,870],"tag":[323,283],"class_list":["post-246651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trouver-sa-voie","category-metiers","tag-fiche-metier","tag-tech"],"acf":[],"_links":{"self":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/posts\/246651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/users\/326"}],"replies":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/comments?post=246651"}],"version-history":[{"count":0,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/posts\/246651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/media\/246660"}],"wp:attachment":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/media?parent=246651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/category?post=246651"},{"taxonomy":"tag","embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/tag?post=246651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}