{"id":189297,"date":"2020-06-09T09:05:10","date_gmt":"2020-06-09T07:05:10","guid":{"rendered":"https:\/\/sherpas.com\/blog\/places-and-forms-of-power-notion-oral-bac-anglais\/"},"modified":"2024-08-29T00:41:29","modified_gmt":"2024-08-28T22:41:29","slug":"places-and-forms-of-power-notion-oral-bac-anglais","status":"publish","type":"post","link":"https:\/\/sherpas.com\/blog\/places-and-forms-of-power-notion-oral-bac-anglais\/","title":{"rendered":"Places and Forms of Power \u00e0 l\u2019expression orale du Bac d\u2019anglais &#8211; M\u00e9thode &amp; Vocabulaire \ud83e\udd34"},"content":{"rendered":"\n<p>Si tu lis ces lignes, c&rsquo;est que tu pr\u00e9pares tes oraux d&rsquo;anglais pour <em>Places and Forms of Power<\/em> avec une once d&rsquo;h\u00e9sitation&#8230;<\/p>\n\n\n\n<p>On est tous pass\u00e9s par l\u00e0 ! C&rsquo;est surement la notion la plus complexe du Bac d&rsquo;anglais, car il faut ma\u00eetriser le contexte social et historique de tous tes exemples en plus de la langue. Mais finalement ce qui compte, c&rsquo;est d&rsquo;avoir la bonne m\u00e9thode, les exemples pertinents et le vocabulaire parfait. C&rsquo;est la raison pour laquelle on t&rsquo;a pr\u00e9m\u00e2ch\u00e9 le travail dans cet article !<\/p>\n\n\n\n<p>Ah, oui, cet article est dans la continuit\u00e9 d&rsquo;une longue s\u00e9rie sur le Bac d&rsquo;anglais qui va t&rsquo;aider \u00e0 booster tes notes : elle est pas belle la vie ? \ud83e\udd73<\/p>\n\n\n\n<p>Et si l&rsquo;ampleur du pouvoir politique te fascine mais que tu peines \u00e0 trouver les mots justes pour ton oral d&rsquo;anglais, pourquoi ne pas explorer nos <strong><a href=\"https:\/\/sherpas.com\/cours\/anglais\">cours d&rsquo;anglais<\/a><\/strong> pour ma\u00eetriser parfaitement ce sujet ? \ud83c\udfdb\ufe0f<\/p>\n\n\n<section class=\"articles articles--vertical articles--3\">\n    <div  class=\"container\" >\n        <div class=\"articles__top\">\n            <p class=\"t-05\"><\/p>\n                    <\/div>\n        <div class=\"row\">\n                                                <div class=\"col-12\n                                                    col-xl-4\n                                            \">\n                        <div\n\n   class=\"article-card-vertical  article-card-vertical--3   \">\n\n            <a href=\"https:\/\/sherpas.com\/blog\/idea-of-progress-notion-oral-bac-anglais\/\">\n            <picture>\n                <img decoding=\"async\" width=\"389\" height=\"272\" src=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/Idea-of-progress-idee-de-progres-oral-bac-anglais-manifestation-demonstration.jpg\" class=\"article-card-vertical__image wp-post-image\" alt=\"Idea of progress id\u00e9e de progr\u00e8s oral bac anglais manifestation demonstration\" ci-src=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/Idea-of-progress-idee-de-progres-oral-bac-anglais-manifestation-demonstration.jpg?q=85\" \/>\n                \n                    \n            <\/picture>\n\n        <\/a>\n     \n  \n    <div class=\"article-card-vertical__content\">\n        <a class=\"article-card-vertical__link\" href=\"https:\/\/sherpas.com\/blog\/idea-of-progress-notion-oral-bac-anglais\/\">\n            <h3 class=\"article-card-vertical__title\" id=\"idea-of-progress-a-lexpression-orale-du-bac-danglais-methode-vocabulaire\">\n                Idea of Progress \u00e0 l\u2019expression orale du Bac d\u2019anglais &#8211; M\u00e9thode &amp; Vocabulaire&nbsp;\ud83d\ude80\n            <\/h3>\n                            <div class=\"article-card-vertical__text\">\n                    L\u2019expression orale d\u2019anglais arrive \u00e0 grands pas et tu ne sais pas comment am\u00e9liorer ta performance pour les (&#8230;)\n                <\/div>\n                    <\/a>   \n                    <div class=\"article-card-vertical__tags\">\n\n                <a href=\"https:\/\/sherpas.com\/blog\/tag\/bac\/\" class=\"article-card-vertical__tag badge\">Bac<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/oral\/\" class=\"article-card-vertical__tag badge\">Oral<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/terminale\/\" class=\"article-card-vertical__tag badge\">Terminale<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/vocabulaire\/\" class=\"article-card-vertical__tag badge\">Vocabulaire<\/a>            <\/div>\n            <\/div>\n<\/div>\n                    <\/div>\n                                    <div class=\"col-12\n                                                    col-xl-4\n                                            \">\n                        <div\n\n   class=\"article-card-vertical  article-card-vertical--3   \">\n\n            <a href=\"https:\/\/sherpas.com\/blog\/myths-and-heroes-notion-oral-bac-anglais\/\">\n            <picture>\n                <img decoding=\"async\" width=\"396\" height=\"264\" src=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/myths-and-heroes-nelson-mandela-sculpture-pretoria.jpg\" class=\"article-card-vertical__image wp-post-image\" alt=\"myths and heroes nelson mandela sculpture pretoria\" ci-src=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/myths-and-heroes-nelson-mandela-sculpture-pretoria.jpg?q=85\" \/>\n                \n                    \n            <\/picture>\n\n        <\/a>\n     \n  \n    <div class=\"article-card-vertical__content\">\n        <a class=\"article-card-vertical__link\" href=\"https:\/\/sherpas.com\/blog\/myths-and-heroes-notion-oral-bac-anglais\/\">\n            <h3 class=\"article-card-vertical__title\" id=\"myths-and-heroes-a-lexpression-orale-du-bac-danglais-methode-vocabulaire\">\n                Myths and Heroes \u00e0 l\u2019expression orale du Bac d\u2019anglais \u2013 M\u00e9thode &amp; Vocabulaire&nbsp;\ud83e\uddb9\n            <\/h3>\n                            <div class=\"article-card-vertical__text\">\n                    S\u2019il y a bien quelque chose qui n\u2019a pas chang\u00e9 avec la r\u00e9forme du bac ce sont les (&#8230;)\n                <\/div>\n                    <\/a>   \n                    <div class=\"article-card-vertical__tags\">\n\n                <a href=\"https:\/\/sherpas.com\/blog\/tag\/bac\/\" class=\"article-card-vertical__tag badge\">Bac<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/oral\/\" class=\"article-card-vertical__tag badge\">Oral<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/terminale\/\" class=\"article-card-vertical__tag badge\">Terminale<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/vocabulaire\/\" class=\"article-card-vertical__tag badge\">Vocabulaire<\/a>            <\/div>\n            <\/div>\n<\/div>\n                    <\/div>\n                                    <div class=\"col-12\n                                                    col-xl-4\n                                            \">\n                        <div\n\n   class=\"article-card-vertical  article-card-vertical--3   \">\n\n            <a href=\"https:\/\/sherpas.com\/blog\/spaces-and-exchanges-notion-oral-bac-anglais\/\">\n            <picture>\n                <img decoding=\"async\" width=\"396\" height=\"264\" src=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/spaces-and-exchanges-espaces-et-echanges-oral-bac-anglais-bateaux-coucher-de-soleil.jpg\" class=\"article-card-vertical__image wp-post-image\" alt=\"spaces and exchanges espaces et \u00e9changes oral bac anglais bateaux coucher de soleil\" ci-src=\"https:\/\/sherpas.com\/content\/uploads\/2021\/10\/spaces-and-exchanges-espaces-et-echanges-oral-bac-anglais-bateaux-coucher-de-soleil.jpg?q=85\" \/>\n                \n                    \n            <\/picture>\n\n        <\/a>\n     \n  \n    <div class=\"article-card-vertical__content\">\n        <a class=\"article-card-vertical__link\" href=\"https:\/\/sherpas.com\/blog\/spaces-and-exchanges-notion-oral-bac-anglais\/\">\n            <h3 class=\"article-card-vertical__title\" id=\"spaces-and-exchanges-a-lexpression-orale-du-bac-danglais-methode-et-vocabulaire\">\n                Spaces and Exchanges \u00e0 l&rsquo;expression orale du Bac d&rsquo;anglais &#8211; M\u00e9thode et Vocabulaire&nbsp;\ud83c\udf0d\n            <\/h3>\n                            <div class=\"article-card-vertical__text\">\n                    Si tu lis ces lignes, c\u2019est que le stress monte pour l\u2019oral du bac d\u2019anglais. C\u2019est bien normal, (&#8230;)\n                <\/div>\n                    <\/a>   \n                    <div class=\"article-card-vertical__tags\">\n\n                <a href=\"https:\/\/sherpas.com\/blog\/tag\/bac\/\" class=\"article-card-vertical__tag badge\">Bac<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/oral\/\" class=\"article-card-vertical__tag badge\">Oral<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/terminale\/\" class=\"article-card-vertical__tag badge\">Terminale<\/a><a href=\"https:\/\/sherpas.com\/blog\/tag\/vocabulaire\/\" class=\"article-card-vertical__tag badge\">Vocabulaire<\/a>            <\/div>\n            <\/div>\n<\/div>\n                    <\/div>\n                                    <\/div>\n    <\/div>\n<\/section>\n\n\n<h2 class=\"wp-block-heading\" id=\"methode-pour-la-notion-lieux-et-formes-de-pouvoir-au-bac-danglais\">M\u00e9thode pour la notion \u00ab\u00a0Lieux et Formes de pouvoir\u00a0\u00bb au bac d&rsquo;anglais \ud83d\udc69\ud83c\udffd\u200d\ud83c\udfeb<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"lintroduction-en-expression-orale\">L\u2019introduction en expression orale<\/h3>\n\n\n\n<p><strong>\u00c9nonce toujours quelle notion tu vas pr\u00e9senter (n\u2019oublie pas que le professeur fait passer jusqu\u2019\u00e0 30 \u00e9l\u00e8ves de suite).<\/strong><\/p>\n\n\n\n<p>\ud83d\udca1 Essaie de d\u00e9finir la notion de mani\u00e8re tr\u00e8s g\u00e9n\u00e9rale, tout en te dirigeant vers l\u2019aspect que tu traites pendant ton expos\u00e9. \u00c9vite de seulement reprendre la d\u00e9finition de ton manuel de cours ou celle de ton\/ta prof, au risque sinon de ne pas te diff\u00e9rencier.<\/p>\n\n\n\n<p><em>Par exemple :<\/em><\/p>\n\n\n\n<p><em>\u201cPower is the ability to influence people\u2019s behaviour. Nowadays, many powers are perceived as established. The economic and political influence exercised in some countries are examples of such established powers.<\/em> <em>Other powers exist in essence, but these are not necessarily as powerful as established powers. Yet, they naturally tend to compete with\/counter these ones.\u201d<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"places-and-forms-of-power-problematique\">Places and Forms of Power &#8211; Probl\u00e9matique<\/h4>\n\n\n\n<p>Ensuite, tu exposes ta probl\u00e9matique. On te conseille de tourner celle-ci de mani\u00e8re \u00e0 pouvoir argumenter pour et contre. Par exemple :<\/p>\n\n\n\n<p><em>\u201cWe will wonder to what extent\u2026\u201d<\/em><\/p>\n\n\n\n<p>Enfin, tu \u00e9nonces ton plan en <strong>une phrase maximum<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"quelques-conseils-pour-le-developpement-de-ta-notion\">Quelques conseils pour le d\u00e9veloppement de ta notion<\/h3>\n\n\n\n<p><strong>\ud83d\udc49\ud83c\udffb  Il est essentiel que tu fiches tes documents au cours de l\u2019ann\u00e9e pour savoir quel document est exploitable ou ne l\u2019est pas.<\/strong> C\u2019est PRI-MOR-DIAL, surtout si ton prof n\u2019est pas organis\u00e9 du tout ! \ud83e\udd2d<\/p>\n\n\n\n<p>Au fait, les compr\u00e9hensions orales \u00e9tudi\u00e9es pendant l&rsquo;ann\u00e9e seront oubli\u00e9es par la moiti\u00e9 de tes camarades ! Profites-en \ud83d\ude09<\/p>\n\n\n\n<p><b>\u00c0 l\u2019aide de ces fiches, r\u00e9fl\u00e9chis \u00e0 ce qui les lie entre-elles, puis ce qui les relie elles-m\u00eames \u00e0 la notion Places and Forms of Power.<\/b> Tu t\u2019es s\u00fbrement d\u00e9j\u00e0 rendu compte que le tiers des points en oral de langue d\u00e9pendent de la r\u00e9flexion plus ou moins pouss\u00e9e de l\u2019\u00e9l\u00e8ve. \ud83c\udfaf<\/p>\n\n\n\n<p><strong>C\u2019est logique apr\u00e8s tout : si tu montres au prof que tu r\u00e9fl\u00e9chis, il va trouver cela plus pertinent que si tu fais une b\u00eate paraphrase&nbsp; des documents !<\/strong><\/p>\n\n\n\n<p>Une fois que ce travail est fait, r\u00e9fl\u00e9chis au plan parfait, et commence tes fiches finales !<\/p>\n\n\n\n<p>\ud83d\udccc  <strong>Comme pour tout expos\u00e9 oral, il faut que ton discours soit extr\u00eamement organis\u00e9.<\/strong> Pour cela, utilise des connecteurs logiques et annonce chaque partie puis chaque sous-partie par une phrase.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/media.giphy.com\/media\/v1.Y2lkPTc5MGI3NjExbTgzdW92bnB6MDQycnBpbGowd2FtdzJiNGZlaG1uOXZybzE3MTFjaCZlcD12MV9naWZzX3NlYXJjaCZjdD1n\/K9BR635xR1Y8ouoU1X\/giphy.gif\" alt=\"femme qui dit &quot;you're organized&quot;\" \/><\/figure>\n<\/div>\n\n\n<p><strong>EXEMPLE 1 pour \u00e9noncer tes grandes parties :<\/strong><br> <em>\u201cTo begin, we will focus on #TITLE PART I#\u2026\u201d<\/em><br> <em>\u201cThe second part of my analysis will be about #TITLE PART 2#&#8230;\u201d<\/em><br> <em>\u201cThen, I will\u00a0 #TITLE PART 3#&#8230;\u201d<\/em><\/p>\n\n\n\n<p><strong>EXEMPLE 2 pour \u00e9noncer tes grandes parties :<\/strong><br>\n<em>\u201cOn the one hand, we will focus on #TITLE PART I#\u2026\u201d<\/em><br>\n<em>\u201cOn the other hand, the problem of #TITLE PART 2# needs careful consideration\u201d<\/em><\/p>\n\n\n\n<p><strong>Exemple pour \u00e9noncer tes sous-parties : \ud83d\udcdd<\/strong><br>\n<em>In order to deal with this issue (part 1), we will review several notions and documents.<\/em><br>\n<em>First of all, a relevant argument to look at was coined by XXX in 1960. The main point was that\u2026 It was used again during this speech that we studied in class.\u2026<\/em><br>\n<em>#Document 1#<\/em><br>\n<em>Furthermore, some proponents of this theory argue that&#8230;<\/em><br>\n<em>#Document 2#<\/em><br>\n<em>Finally, an additional argument to support this assertion is&#8230;<\/em><br>\n<em>#Document 3#<\/em><\/p>\n\n\n<section class=\"push \">\n        <div >\n            \n                                                <div class=\"push__container  qcd\" data-target=\"_self\" data-qcd=\"aHR0cHM6Ly9zaGVycGFzLmNvbS9mdW5uZWwtc3R1ZGVudC1xdWFsaWZpY2F0aW9u\" data-banner=\"2\" data-name=\"CPM1 Anglais\" style=\"background-color: #F3FBF7\" >\n                                                                        <div class=\"push__teachers\">\n    <div class=\"d-flex justify-content-center d-md-none\">\n        <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\" alt=\"Logo Sherpas\">\n    <\/div>\n    <div class=\"swiper\">\n        <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Jade2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Jade<\/p>                          <p class=\"push__teachers-school\">Sciences Po Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">21\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Cle\u0301mence2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Cl\u00e9mence<\/p>                          <p class=\"push__teachers-school\">HEC Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">21\u20ac\/h\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Olivier2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Olivier<\/p>                          <p class=\"push__teachers-school\">La Sorbonne<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">13\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Pierre2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Pierre<\/p>                          <p class=\"push__teachers-school\">ESSEC<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">16\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Emilie2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Emilie<\/p>                          <p class=\"push__teachers-school\">Sciences Po Lyon<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Antoine2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Antoine<\/p>                          <p class=\"push__teachers-school\">Sciences Po Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">18\u20ac\/h\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Margot2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Margot<\/p>                          <p class=\"push__teachers-school\">Arts et M\u00e9tiers ParisTech<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">22\u20ac\/h\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Thibault2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Thibault<\/p>                          <p class=\"push__teachers-school\">ENS Paris Ulm<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">20\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                                                    <div class=\"push__content\">\n                                                            <div  class=\"d-none d-md-block\" >\n                                    <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\"\n                                        alt=\"Logo Sherpas\">\n                                <\/div>\n                                                                                        <div class=\"push__title\"><p>Besoin d&rsquo;un <span style=\"color: #4cc583;\">prof particulier<\/span> d&rsquo;anglais ? <span role=\"image\" aria-label=\"\u2728\">\u2728<\/span><\/p>\n<\/div>\n                                                                                        <div class=\"push__text\"><p>Nos Sherpas sont l\u00e0 pour t&rsquo;aider \u00e0 progresser et prendre confiance en toi !<\/p>\n<\/div>\n                                                        <div class=\"push__promo-button   \">\n                                                                                                    <div\n                                        class=\"btn btn-primary\"\n                                        style=\"color: ; border-color: ; background-color: \"\n\n                                    >\n                                        JE PRENDS UN COURS OFFERT !\n                                    <\/div>\n                                                            <\/div>\n                                                    <\/div>\n                                    <\/div>\n                                    <\/div>\n    <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"themes-et-exemples-a-aborder-pour-places-and-forms-of-power-a-lexpression-orale\">Th\u00e8mes et exemples \u00e0 aborder pour \u201cPlaces and Forms of Power\u201d \u00e0 l&rsquo;expression orale<\/h2>\n\n\n\n<p><strong>Suivant ce que tu as \u00e9tudi\u00e9 en cours, tu peux diviser les formes de pouvoir en deux ou trois groupes distincts. Par exemple :<\/strong><\/p>\n\n\n\n<p>\u201cStrong\u201d power : Political, Economic and financial<\/p>\n\n\n\n<p>\u201cSoft\u201d power : Ideological, Cultural and social (e.g. arts and languages)<\/p>\n\n\n\n<p>\ud83d\udc49<strong>  Let\u2019s have a look at some examples together \ud83d\ude0b<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"political-power\">Political power \ud83d\udc68\u200d\ud83d\udcbc<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"the-cold-war-and-the-vietnam-war\">The Cold War and the Vietnam War \ud83d\udca3<\/h4>\n\n\n\n<p>A few examples of themes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>the nuclear arms race<\/li>\n\n\n\n<li>the space race and the first steps on the Moon<\/li>\n\n\n\n<li><em>Ich bin ein Berliner<\/em> speech by JFK<\/li>\n\n\n\n<li>Popular protests against the Vietnam War<\/li>\n\n\n\n<li>The massacres of the Vietnam War (My Lai, Speedy Express)<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"colonization-and-decolonization-the-example-of-india\">Colonization and Decolonization : the example of India \ud83d\udd0e<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Counterpowers and Gandhi<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"economic-and-financial-power\">Economic and financial power \ud83d\udcb5<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"faang-facebook-amazon-apple-netflix-google\">FAANG (Facebook, Amazon, Apple, Netflix, Google)<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>The role of Facebook in elections nowadays<\/li>\n\n\n\n<li>Google and Apple economic power and controversies<\/li>\n\n\n\n<li>The role of American corporations during the Cold War : Coca-Cola<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ideological-power\">Ideological power \ud83d\udca1<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"mccarthyism-and-the-hollywood-blacklist\">McCarthyism and the Hollywood Blacklist<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>the example of Charlie Chaplin<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"cultural-and-social-power\">Cultural and social power \ud83d\uddfd<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"india-in-the-english-speaking-world\">India in the English-speaking world<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>the power of the Indian caste<\/li>\n\n\n\n<li>Indian traditions and rituals<\/li>\n\n\n\n<li>Indian migrants and their integration worldwide<\/li>\n<\/ul>\n\n\n\n<p>\u26a0\ufe0f  Nous avons choisi ces th\u00e8mes, car ils sont r\u00e9currents dans les manuels d\u2019anglais de Terminale, mais les arguments que tu s\u00e9lectionnes d\u00e9pendent du contexte de chaque document vu en cours.<\/p>\n\n\n\n<p>\ud83d\udca1 Ces th\u00e8mes peuvent \u00eatre utilis\u00e9s comme une inspiration si tu n\u2019as pas vu de documents en cours sur le sujet ou si tu souhaites faire une ouverture par exemple.<\/p>\n\n\n<section class=\"push \">\n        <div >\n            \n                                                <div class=\"push__container  qcd\" data-target=\"_self\" data-qcd=\"aHR0cHM6Ly9zaGVycGFzLmNvbS9mdW5uZWwtc3R1ZGVudC1xdWFsaWZpY2F0aW9u\" data-banner=\"2\" data-name=\"CPM2 Anglais\" style=\"background-color: #F3FBF7\" >\n                                                                        <div class=\"push__teachers\">\n    <div class=\"d-flex justify-content-center d-md-none\">\n        <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\" alt=\"Logo Sherpas\">\n    <\/div>\n    <div class=\"swiper\">\n        <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Sophie2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Sophie<\/p>                          <p class=\"push__teachers-school\">Sciences Po Bordeaux<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">12\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Martin2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Martin<\/p>                          <p class=\"push__teachers-school\">HEC Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">23\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Agathe2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Agathe<\/p>                          <p class=\"push__teachers-school\">ENS Lyon<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Victor2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Victor<\/p>                          <p class=\"push__teachers-school\">ESCP<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">25\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Alma2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Alma<\/p>                          <p class=\"push__teachers-school\">ENS Paris-Saclay<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">24\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Jeanne2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Jeanne<\/p>                          <p class=\"push__teachers-school\">Aix-Marseille Universit\u00e9<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">17\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/David2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">David<\/p>                          <p class=\"push__teachers-school\">EDHEC<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">25\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/2022\/01\/Emma2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Emma<\/p>                          <p class=\"push__teachers-school\">Dauphine<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">15\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                                                    <div class=\"push__content\">\n                                                            <div  class=\"d-none d-md-block\" >\n                                    <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\"\n                                        alt=\"Logo Sherpas\">\n                                <\/div>\n                                                                                        <div class=\"push__title\"><p>Ton premier <span style=\"color: #4cc483;\">cours particulier<\/span> d&rsquo;anglais est <span style=\"color: #4cc483;\">offert<\/span> ! <span role=\"image\" aria-label=\"\ud83c\udf81\">\ud83c\udf81<\/span><\/p>\n<\/div>\n                                                                                        <div class=\"push__text\"><p>Tous nos profs sont pass\u00e9s par les meilleures \u00e9coles de France !<\/p>\n<\/div>\n                                                        <div class=\"push__promo-button   \">\n                                                                                                    <div\n                                        class=\"btn btn-primary\"\n                                        style=\"color: ; border-color: ; background-color: \"\n\n                                    >\n                                        J\u2019EN PROFITE !\n                                    <\/div>\n                                                            <\/div>\n                                                    <\/div>\n                                    <\/div>\n                                    <\/div>\n    <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"vocabulaire-essentiel-pour-places-and-forms-of-power-a-loral-du-bac-danglais\">Vocabulaire essentiel pour \u201cPlaces and Forms of Power\u201d \u00e0 l&rsquo;oral du bac d&rsquo;anglais \ud83e\uddfe<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vocabulaire-du-strong-power\">Vocabulaire du \u201cStrong power\u201d<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em><strong>an arsenal (of nuclear weapons for e.g.)<\/strong><\/em> : un arsenal d\u2019armes nucl\u00e9aires<\/li>\n\n\n\n<li><em><strong>a fleet<\/strong><\/em> : une flotte<\/li>\n\n\n\n<li><em><strong>the Navy<\/strong><\/em> : la marine nationale (US)<\/li>\n\n\n\n<li><em><strong>the national pride<\/strong><\/em> : la fiert\u00e9 nationale<\/li>\n\n\n\n<li><em><strong>powerful, influential<\/strong><\/em> : puissant, influent<\/li>\n\n\n\n<li><em><strong>to commemorate<\/strong><\/em> : comm\u00e9morer<\/li>\n\n\n\n<li><strong><em>to trigger, to provoke<\/em><\/strong> : d\u00e9clencher<\/li>\n\n\n\n<li><em><strong>the arms race<\/strong><\/em> : la course \u00e0 l\u2019armement<\/li>\n\n\n\n<li><em><strong>a balance<\/strong><\/em> : un \u00e9quilibre<\/li>\n\n\n\n<li><em><strong>derisory, ridiculous<\/strong><\/em> : d\u00e9risoire<\/li>\n\n\n\n<li><em><strong>impressed, fascinated<\/strong><\/em> : fascin\u00e9<\/li>\n\n\n\n<li><em><strong>to deter somebody from doing something<\/strong><\/em> : dissuader qqn de faire qqch<\/li>\n\n\n\n<li><em><strong>to intimidate<\/strong> <\/em>: intimider<\/li>\n\n\n\n<li><em><strong>to put pressure on<\/strong> <\/em>: faire pression sur<\/li>\n\n\n\n<li><em><strong>astounded, startled<\/strong> <\/em>: \u00e9tonn\u00e9, stup\u00e9fait<\/li>\n\n\n\n<li><strong>c<\/strong><em><strong>rippled, disabled<\/strong><\/em> : handicap\u00e9<\/li>\n\n\n\n<li><em><strong>a bloodstain<\/strong><\/em> : une t\u00e2che de sang<\/li>\n\n\n\n<li><em><strong>mistrustful, suspicious<\/strong><\/em> : m\u00e9fiant, suspicieux<\/li>\n\n\n\n<li><em><strong>to distrust somebody<\/strong><\/em> : se m\u00e9fier de qqn<\/li>\n\n\n\n<li><em><strong>to find out, to discover<\/strong><\/em> : d\u00e9couvrir<\/li>\n\n\n\n<li><em><strong>to keep somebody from harm, to protect<\/strong><\/em> : prot\u00e9ger<\/li>\n\n\n\n<li><em><strong>a campaigner, an activist<\/strong><\/em> : un activiste<\/li>\n\n\n\n<li><em><strong>a counterpower<\/strong><\/em> : un contre-pouvoir<\/li>\n\n\n\n<li><em><strong>a demonstration, a protest<\/strong><\/em> : une manifestation<\/li>\n\n\n\n<li><em><strong>a demonstrator, a protester<\/strong><\/em> : un manifestant<\/li>\n\n\n\n<li><em><strong>to march, to take the streets, to demonstrate<\/strong><\/em> : manifester<\/li>\n\n\n\n<li><em><strong>to gather, to rally<\/strong><\/em> : rassembler, r\u00e9unir<\/li>\n\n\n\n<li><em><strong>hawkish<\/strong> <\/em>: belliqueux<\/li>\n\n\n\n<li><em><strong>pacifist<\/strong> <\/em>: pacifiste<\/li>\n\n\n\n<li><em><strong>to advocate<\/strong><\/em> : un d\u00e9fenseur<\/li>\n\n\n\n<li><em><strong>to empower<\/strong><\/em> : dynamiser<\/li>\n\n\n\n<li><em><strong>to spur\/to trigger a protest movement<\/strong><\/em> : encourager un mouvement de protestation<\/li>\n\n\n\n<li><em><strong>a draft dodger<\/strong><\/em> : un insoumis<\/li>\n\n\n\n<li><em><strong>an idealist<\/strong><\/em> : un id\u00e9aliste<\/li>\n\n\n\n<li><em><strong>to be determined<\/strong><\/em> : \u00eatre d\u00e9termin\u00e9<\/li>\n\n\n\n<li><em><strong>to be hopeful<\/strong> <\/em>: \u00eatre optimiste<\/li>\n\n\n\n<li><em><strong>to account for, to explain<\/strong><\/em> : expliquer<\/li>\n\n\n\n<li><em><strong>to do something for the better<\/strong><\/em><\/li>\n\n\n\n<li><em><strong>to flee, to run away from<\/strong><\/em> : fuir, s\u2019enfuir<\/li>\n\n\n\n<li><em><strong>to fulfil one\u2019s dream, to make one\u2019s dream come true<\/strong><\/em> : r\u00e9aliser ses r\u00eaves<\/li>\n\n\n\n<li><em><strong>to be committed <\/strong><\/em>: \u00eatre engag\u00e9<\/li>\n\n\n\n<li><em><strong>cannon fodder<\/strong><\/em> : chair \u00e0 canon<\/li>\n\n\n\n<li><em><strong>to enlist<\/strong><\/em> : s\u2019engager<\/li>\n\n\n\n<li><em><strong>to raise awareness<\/strong><\/em> : susciter une prise de conscience<\/li>\n\n\n\n<li><em><strong>to stand up for one\u2019s right, to fight for<\/strong><\/em> : se battre pour<\/li>\n\n\n\n<li><em><strong>to stand up to, to oppose, to resist<\/strong><\/em> : r\u00e9sister \u00e0<\/li>\n\n\n\n<li><em><strong>bravery<\/strong><\/em> : le courage<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vocabulaire-du-soft-power\">Vocabulaire du \u201cSoft power\u201d \ud83d\udcfb<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em><strong>a folk dance, a traditional dance<\/strong><\/em> : danse populaire<\/li>\n\n\n\n<li><em><strong>an official visit<\/strong><\/em><\/li>\n\n\n\n<li><em><strong>a protocol<\/strong><\/em><\/li>\n\n\n\n<li><em><strong>entertaining<\/strong> <\/em>: divertissant<\/li>\n\n\n\n<li><em><strong>mighty, powerful<\/strong><\/em> : impuissant, puissant<\/li>\n\n\n\n<li><em><strong>to display power<\/strong><\/em> : la d\u00e9monstration de force<\/li>\n\n\n\n<li><em><strong>to impress<\/strong><\/em> : impressionner<\/li>\n\n\n\n<li><em><strong>to make an impression on somebody<\/strong><\/em> : impressionner qqn<\/li>\n\n\n\n<li><em><strong>to spread<\/strong><\/em> : propager<\/li>\n\n\n\n<li><em><strong>a scheme, a plan<\/strong><\/em> : un projet, un complot<\/li>\n\n\n\n<li><em><strong>appealing, pleasing<\/strong><\/em> : agr\u00e9able, s\u00e9duisant<\/li>\n\n\n\n<li><em><strong>compelling, strong<\/strong><\/em> : convaincant<\/li>\n\n\n\n<li><em><strong>unrivalled, unequalled<\/strong><\/em> : in\u00e9gal\u00e9, incomparable<\/li>\n\n\n\n<li><em><strong>to come up with something, to produce something<\/strong><\/em><\/li>\n\n\n\n<li><em><strong>to promote, to make something popular<\/strong><\/em><\/li>\n\n\n\n<li><em><strong>to prompt, to give rise to<\/strong><\/em> : d\u00e9clencher qqch<\/li>\n\n\n\n<li><em><strong>a motive force<\/strong> <\/em>: un \u00e9l\u00e9ment moteur<\/li>\n\n\n\n<li><em><strong>groundbreaking, innovative<\/strong><\/em> : r\u00e9volutionnaire, innovant<\/li>\n\n\n\n<li><em><strong>to partake in something, to participate in something<\/strong><\/em> : participer \u00e0 qqch<\/li>\n\n\n\n<li><em><strong>to spur, to incite<\/strong><\/em> : inciter<\/li>\n\n\n\n<li><em><strong>a religious leader<\/strong><\/em> : un leader religieux<\/li>\n\n\n\n<li><em><strong>a range of, a variety of<\/strong> <\/em>: une vari\u00e9t\u00e9 de<\/li>\n\n\n\n<li><em><strong>to ascertain, to verify<\/strong><\/em> : v\u00e9rifier, d\u00e9terminer<\/li>\n\n\n\n<li><em><strong>to distort, to misrepresent<\/strong><\/em> : fausser, d\u00e9former<\/li>\n\n\n\n<li><em><strong>a prejudic<\/strong><strong>e<\/strong> <\/em>: un pr\u00e9jug\u00e9<\/li>\n\n\n\n<li><em><strong>stiff, rigid<\/strong> <\/em>: rigide<\/li>\n\n\n\n<li><em><strong>to be denied access to<\/strong><\/em> : se voir refuser l\u2019acc\u00e8s \u00e0<\/li>\n\n\n\n<li><em><strong>to be discriminated against<\/strong> <\/em>: subir une discrimination<\/li>\n\n\n\n<li><em><strong>to be victimised<\/strong><\/em> : \u00eatre pers\u00e9cut\u00e9<\/li>\n\n\n\n<li><em><strong>to climb the social ladder<\/strong> <\/em>: s\u2019\u00e9lever dans l\u2019\u00e9chelle sociale<\/li>\n\n\n\n<li><em><strong>to ostracize<\/strong><\/em> : ostraciser<\/li>\n\n\n\n<li><em><strong>to stand in sharp contrast with<\/strong><\/em> : contraster fortement avec<\/li>\n<\/ul>\n\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p>On t&rsquo;aide \u00e0 atteindre le 20 au Bac d&rsquo;anglais \ud83d\ude0e<br data-rich-text-line-break=\"true\" \/>\u2705\u00a0 Jette un \u0153il \u00e0 la <a href=\"https:\/\/sherpas.com\/blog\/methode-expression-ecrite-anglais-bac\/\">m\u00e9thode de l&rsquo;expression \u00e9crite<\/a> \ud83d\udcdd<br data-rich-text-line-break=\"true\" \/>\u2705\u00a0 Tu peux \u00e9galement lire notre <a href=\"https:\/\/sherpas.com\/blog\/comprehension-ecrite-anglais-bac\/\">m\u00e9thode de compr\u00e9hension \u00e9crite<\/a> \u2712\ufe0f<br data-rich-text-line-break=\"true\" \/>\u2705\u00a0 Comment avoir 18+ au bac d&rsquo;anglais ? La r\u00e9ponse dans <a href=\"https:\/\/sherpas.com\/blog\/oral-langues-prepa-bac\/\">cet article<\/a> \ud83c\udf89<strong data-rich-text-format-boundary=\"true\"><br data-rich-text-line-break=\"true\" \/><\/strong><\/p>\n\n        <\/div>\n    <\/section>\n\n\n<section class=\"video\">\n    <div class=\"container\">\n        <div class=\"row justify-content-center\">\n            <div class=\"col-12 col-lg-10\">\n                <div class=\"embed-responsive embed-responsive-16by9\">\n                <iframe src=\"https:\/\/www.youtube.com\/embed\/mDvh9RwkB3o\"\n                        title=\"YouTube video player\" frameborder=\"0\"\n                        allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\"\n                        allowfullscreen><\/iframe>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<p class=\"has-text-align-center\"><em>Tu veux am\u00e9liorer ton accent en anglais ? Regarde cette vid\u00e9o \ud83d\ude09<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"conclusion-sur-la-notion-lieux-et-formes-de-pouvoir\">Conclusion sur la notion \u00ab\u00a0Lieux et Formes de pouvoir\u00a0\u00bb \ud83d\udc40<\/h2>\n\n\n\n<p>\ud83d\udc49  T\u00e2che de rester objectif dans tes propos et ne t\u2019engage pas dans une discussion politique sauf si l\u2019\u00e9valuateur te le demande explicitement ! Si c&rsquo;est le cas, soit mesur\u00e9, et montre toujours que tu prends en compte les points de vue des diff\u00e9rentes parties prenantes (1), m\u00eame si telle position te semble meilleure, pour telle raison (2).<\/p>\n\n\n\n<p>\ud83d\udc49  Renseigne-toi bien sur le contexte historique, social ou politique de chaque document pour ne pas te faire pi\u00e9ger. Dans la mesure du possible, essaie d&rsquo;avoir une opinion un peu construite sur chaque texte pour pouvoir discuter avec ton examinateur s&rsquo;il le souhaite.<\/p>\n\n\n\n<p>\ud83d\udc49  Si jamais tu oublies un argument, ne panique pas ! Cela arrive ! Tu peux dire quelque chose comme : <em>\u201cI am sorry I got lost. May I take a few seconds to organise my thoughts please ?\u201d<\/em> \ud83d\ude4c<\/p>\n\n\n\n<p>\ud83d\udde3\ufe0f Pr\u00eat \u00e0 d\u00e9battre des \u00ab\u00a0Forms of Power\u00a0\u00bb avec aisance \u00e0 l&rsquo;oral ? Nos <strong><a href=\"https:\/\/sherpas.com\/cours\/conversation-anglaise\">cours de conversation en anglais<\/a><\/strong> te pr\u00e9parent \u00e0 argumenter avec assurance, en utilisant le vocabulaire pr\u00e9cis et nuanc\u00e9 que les examinateurs recherchent.<\/p>\n\n\n\n<p><em>No doubt, you will do it ! <\/em>\ud83d\ude80<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;189297&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;5&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.4&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Tu as aim\u00e9 cet article ?&quot;,&quot;legend&quot;:&quot;4.4\\\/5 - (5 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Places and Forms of Power \u00e0 l\u2019expression orale du Bac d\u2019anglais - M\u00e9thode \\u0026amp; Vocabulaire \ud83e\udd34&quot;,&quot;width&quot;:&quot;125.1&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 125.1px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            4.4\/5 - (5 votes)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si tu lis ces lignes, c&rsquo;est que tu pr\u00e9pares tes oraux d&rsquo;anglais pour Places and Forms of Power (&#8230;)<\/p>\n","protected":false},"author":159,"featured_media":163504,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"category":[803,815,800],"tag":[317,79,425,355,298],"class_list":["post-189297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprendre-matiere","category-anglais-2","category-preparation-oral","tag-bac","tag-lycee","tag-oral","tag-terminale","tag-vocabulaire"],"acf":[],"_links":{"self":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/posts\/189297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/comments?post=189297"}],"version-history":[{"count":0,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/posts\/189297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/media\/163504"}],"wp:attachment":[{"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/media?parent=189297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/category?post=189297"},{"taxonomy":"tag","embeddable":true,"href":"https:\/\/sherpas.com\/blog\/wp-json\/wp\/v2\/tag?post=189297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}