{"id":268874,"date":"2025-02-27T14:09:57","date_gmt":"2025-02-27T13:09:57","guid":{"rendered":"https:\/\/sherpas.com\/blog\/parents\/?p=268874"},"modified":"2025-02-27T14:10:02","modified_gmt":"2025-02-27T13:10:02","slug":"accompagner-enfant-alternance","status":"publish","type":"post","link":"https:\/\/sherpas.com\/blog\/parents\/a\/accompagner-enfant-alternance\/","title":{"rendered":"Accompagner mon enfant dans son alternance \ud83e\udd1d"},"content":{"rendered":"\n<p>L&rsquo;alternance est synonyme de<strong> fin d\u2019\u00e9tudes et d&rsquo;insertion professionnelle<\/strong>. En bref, c\u2019est une \u00e9tape cruciale pour chaque jeune adulte qui d\u00e9cide d\u2019opter pour ce type de formation. \ud83d\udd1a<\/p>\n\n\n\n<p>Votre enfant sera sans doute alternant, d\u00e8s la rentr\u00e9e prochaine, on vous donne <strong>les informations et les conseils n\u00e9cessaires afin que vous l\u2019accompagniez du mieux possible<\/strong> ! \ud83d\ude80<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"lalternance-cest-quoi\">L\u2019alternance, c\u2019est quoi ? \ud83e\udd14<\/h2>\n\n\n\n<p>Commen\u00e7ons d\u00e9j\u00e0 par en apprendre un peu plus sur cette formation si particuli\u00e8re qu\u2019est le parcours en alternance.&nbsp;<\/p>\n\n\n<section class=\"relance\">\n        <div >\n                            <a target=\"_blank\" href=\"https:\/\/sherpas.com\/cours\/soutien-scolaire\">\n                    <div class=\"relance__container\"\n                        >\n                        \n                                                        <picture>\n                            <source srcset=\"https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/relance-cours-particulier-1-scaled.jpg\" media=\"(min-width: 999px)\">\n                            <source srcset=\"https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/relance-cours-particulier-1-scaled.jpg\" media=\"(max-width: 999px)\">\n                                <img decoding=\"async\"\n                                    src=\"https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/relance-cours-particulier-1-scaled.jpg\"\n                                    alt=\"Cours particuliers\"\n                                >\n                            <\/picture>\n                                                <div class=\"relance__content\">\n                            \n                                <div class=\"relance__title\"> <p>Votre enfant a des difficult\u00e9s en classe ? Son premier cours particulier est gratuit !<\/p>\n<\/div>\n                                                        <button type=\"button\"\n                                    class=\"relance__button btn btn-white\">\n                                Trouvez un prof de soutien scolaire !\n                            <\/button>\n                        <\/div>\n                    <\/div>\n                <\/a>\n                    <\/div>\n    <\/section>\n\n    \n\n\n<h3 class=\"wp-block-heading\" id=\"definition\">D\u00e9finition \ud83d\udd8a\ufe0f<\/h3>\n\n\n<section class=\"you-know\">\n                <div class=\"you-know__title\"><p><strong>\ud83d\udca1<\/strong><\/p>\n<\/div>\n                        <div class=\"you-know__text\">\n            <p>L\u2019alternance est un syst\u00e8me qui permet \u00e0 celui qui choisit d\u2019opter pour ce type de formation, d\u2019alterner (comme son nom l\u2019indique) entre des phases th\u00e9oriques au sein d\u2019un \u00e9tablissement scolaire et pratiques dans une entreprise.<\/p>\n<p>&nbsp;<\/p>\n<p>En bref, un alternant, pendant la dur\u00e9e de son contrat, doit varier entre les moments o\u00f9 il est \u00e0 l\u2019\u00e9cole en train d\u2019\u00e9tudier et les jours \/ semaines o\u00f9 il travaille dans le cadre professionnel.<\/p>\n<p>&nbsp;<\/p>\n<p>Le rythme (qui se r\u00e9p\u00e8te en boucle) est souvent de :<\/p>\n<p>&nbsp;<\/p>\n<p>Trois semaines en entreprise \/ une semaine \u00e0 l\u2019\u00e9cole<\/p>\n<p>&nbsp;<\/p>\n<p>OU quatre jours en entreprise \/ un jour \u00e0 l&rsquo;\u00e9cole<\/p>\n\n        <\/div>\n              <\/section>\n\n\n\n<p><strong>Deux diff\u00e9rents types de contrats existent<\/strong> lorsqu\u2019on souhaite effectuer une formation en alternance :&nbsp;<\/p>\n\n\n\n<p>\u2712\ufe0f <strong>Le contrat d\u2019apprentissage<\/strong><\/p>\n\n\n\n<p>\u2712\ufe0f <strong>Le contrat de professionnalisation<\/strong>&nbsp;<\/p>\n\n\n\n<p>La diff\u00e9rence ? D\u2019un c\u00f4t\u00e9,<strong> le contrat d\u2019apprentissage permet \u00e0 l\u2019apprenti d\u2019obtenir ou plut\u00f4t de valider un dipl\u00f4me<\/strong> tel que le BTS, CAP ou Master. De l\u2019autre, <strong>le contrat pro<\/strong> n\u2019aboutit pas \u00e0 l\u2019obtention d\u2019un dipl\u00f4me, mais<strong> permet d\u2019acqu\u00e9rir une qualification professionnelle<\/strong>, en vue d\u2019acc\u00e9der \u00e0 un emploi en particulier. \ud83d\udcaa<\/p>\n\n\n\n<p>Si vous souhaitez en savoir plus sur les caract\u00e9ristiques (\u00e2ge requis, salaire, dur\u00e9e de contrat\u2026) de ces deux contrats d&rsquo;alternance, on vous renvoie \u00e0 <a href=\"https:\/\/sherpas.com\/blog\/pourquoi-choisir-lalternance\/\">notre article sur le sujet<\/a> ! \ud83d\udc49<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"les-avantages-de-lalternance\">Les avantages de l\u2019alternance \ud83d\udd25<\/h3>\n\n\n\n<p>Fin avril 2024, on d\u00e9nombrait pas moins de <strong>991 000 apprentis en France, soit une augmentation de 4,9 % sur un an<\/strong>. (<a href=\"https:\/\/poem.travail-emploi.gouv.fr\/synthese\/contrats-d-apprentissage#:~:text=contrats%20d&#039;apprentissage.-,Fin%20avril%202024%2C%20on%20compte%20991%20000%20apprentis%2C%20soit%20une,%25%20pour%20ceux%20du%20public).\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">chiffres de la Direction de l&rsquo;Animation de la Recherche, des \u00c9tudes et des Statistiques<\/a>) \ud83d\udcc8<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"483\" height=\"754\" src=\"https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png\" alt=\"Nombre d'alternants \" class=\"wp-image-268875\" style=\"width:319px;height:auto\" srcset=\"https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=483 483w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=192 192w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=80 80w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=174 174w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=282 282w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=238 238w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=241 241w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-104528.png?q=90&amp;org_if_sml=1&amp;w=38 38w\" sizes=\"(max-width: 483px) 100vw, 483px\" \/><figcaption class=\"wp-element-caption\"><em>Source : Dares &#8211;&nbsp; Syst\u00e8me d&rsquo;Information sur l&rsquo;Apprentissage &#8211; Politiques de L\u2019Emploi<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Qu\u2019il soit en <a href=\"https:\/\/sherpas.com\/blog\/parents\/a\/cap-bts-dut-differences\/\">CAP, BTS, Master <\/a>ou en r\u00e9insertion professionnelle, votre enfant a donc la possibilit\u00e9 de faire une alternance. Mais<strong> pourquoi opter pour cette solution plut\u00f4t que pour un parcours \u201cclassique\u201d ? \ud83d\udc40<\/strong><\/p>\n\n\n\n<p>Voici les avantages d\u2019une telle formation :&nbsp;<\/p>\n\n\n\n<p><strong>\ud83d\udcda L\u2019exp\u00e9rience<\/strong> : en effet, votre enfant, en \u00e9tant alternant, va certes ajouter une ligne \u00e0 son CV, mais surtout accumuler de l\u2019exp\u00e9rience professionnelle avant d&rsquo;entrer ou de se r\u00e9ins\u00e9rer dans le monde du travail. Et ce n\u2019est pas le cas des \u00e9tudiants qui passent par un parcours \u201cclassique\u201d, g\u00e9n\u00e9ralement trop th\u00e9orique.<\/p>\n\n\n\n<p><strong>\ud83d\udcb6 La question mon\u00e9taire<\/strong> : point \u00e0 ne pas n\u00e9gliger, l\u2019entreprise de votre enfant \u201cpaye son \u00e9cole\u201d. Si cette derni\u00e8re lui co\u00fbte 9 000 \u20ac \u00e0 l\u2019ann\u00e9e, sachez qu\u2019il n\u2019aura pas un centime \u00e0 d\u00e9verser et que c\u2019est sa bo\u00eete qui se chargera de r\u00e9gler ses frais de scolarit\u00e9, directement \u00e0 son \u00e9tablissement.<\/p>\n\n\n\n<p>Une petite ann\u00e9e d\u2019\u00e9tude gratuite, on ne dit pas non !&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/media.giphy.com\/media\/94EQmVHkveNck\/giphy.gif?cid=ecf05e474jjtzr8ahe8z380ht32jzmlr7g9s5a759uk3nokq&amp;ep=v1_gifs_search&amp;rid=giphy.gif&amp;ct=g\" alt=\"Se moucher avec des billets\"\/><\/figure>\n<\/div>\n\n<section class=\"you-know\">\n                <div class=\"you-know__title\"><p>\u26a0\ufe0f Attention \u26a0\ufe0f<\/p>\n<\/div>\n                        <div class=\"you-know__text\">\n            <p data-start=\"23\" data-end=\"238\">\u00c0 partir du <strong data-start=\"35\" data-end=\"47\">1er mars<\/strong>, les apprentis gagnant <strong data-start=\"71\" data-end=\"95\">au moins 50% du Smic<\/strong> (environ <strong data-start=\"105\" data-end=\"118\">900\u20ac brut<\/strong>) seront soumis \u00e0 la <strong data-start=\"139\" data-end=\"157\">CSG et la CRDS<\/strong> (contributions sociales). Cela signifie une l\u00e9g\u00e8re baisse de leur salaire net, eh oui&#8230;<\/p>\n<p data-start=\"240\" data-end=\"380\"><strong data-start=\"243\" data-end=\"265\">Qui est concern\u00e9 ?<\/strong><\/p>\n<p data-start=\"240\" data-end=\"380\">\u27a1\ufe0f <strong data-start=\"271\" data-end=\"296\">Les nouveaux contrats<\/strong> sign\u00e9s \u00e0 partir du 1er mars.<br data-start=\"325\" data-end=\"328\" \/>\u27a1\ufe0f <strong data-start=\"331\" data-end=\"378\">Les contrats en cours ne sont pas impact\u00e9s.<\/strong><\/p>\n<p data-start=\"382\" data-end=\"476\" data-is-last-node=\"\" data-is-only-node=\"\">\ud83d\udd0e Chers Parents,<strong> informez-vous !<\/strong> Cette mesure peut malheureusement modifier le budget de votre enfant apprenti.<\/p>\n\n        <\/div>\n              <\/section>\n\n\n\n<p><strong>\ud83d\udca5 L\u2019insertion professionnelle<\/strong> : un crit\u00e8re et pas des moindres, celui de l\u2019avenir et de l\u2019entr\u00e9e dans la vie active. <a href=\"https:\/\/publication.enseignementsup-recherche.gouv.fr\/eesr\/FR\/EESR15_ES_26\/l_insertion_professionnelle_des_alternants_de_l_enseignement_superieur\/#:~:text=En%20mati%C3%A8re%20d&#039;insertion%2C%20l,voie%20scolaire%20(graphique%2026.02).\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Selon une \u00e9tude du minist\u00e8re de l\u2019Enseignement sup\u00e9rieur<\/a>, 63 % des alternants, une fois leur formation finie, acc\u00e8dent imm\u00e9diatement \u00e0 leur 1er emploi alors que c&rsquo;est le cas pour \u201cseulement\u201d 45 % des \u00e9tudiants sortant de la voie scolaire (sans alternance).&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1447\" height=\"736\" src=\"https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?func=bound&amp;w=1024&amp;h=736\" alt=\"Temps d'acc\u00e8s au premier emploi selon le plus haut dipl\u00f4me obtenu et la voie de formation la derni\u00e8re ann\u00e9e d'\u00e9tudes\" class=\"wp-image-268876\" style=\"width:770px;height:auto\" srcset=\"https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=1447 1447w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=300 300w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=1024 1024w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=768 768w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=200 200w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=396 396w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=288 288w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=610 610w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=265 265w, https:\/\/xapbm7c37i.cloudimg.io\/https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2024\/07\/Capture-decran-2024-07-15-113214.png?q=90&amp;org_if_sml=1&amp;w=60 60w\" sizes=\"(max-width: 1447px) 100vw, 1447px\" \/><figcaption class=\"wp-element-caption\"><em>C\u00e9req 2020\/2021<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Mais il ne faut pas croire que tout est rose en alternance, <strong>un \u00e9tudiant doit aussi savoir g\u00e9rer son temps entre l\u2019\u00e9cole et l\u2019entreprise<\/strong>. La transition entre les deux univers n\u2019est pas toujours \u00e9vidente, l\u2019alternant se doit donc d\u2019\u00eatre organis\u00e9 et un minimum rigoureux, pas question de fl\u00e2ner malheureusement\u2026 \ud83d\ude34<\/p>\n\n\n<section class=\"you-know\">\n                <div class=\"you-know__title\"><p>\ud83d\udd0e La recherche d\u2019entreprise<\/p>\n<\/div>\n                        <div class=\"you-know__text\">\n            <p>Comme pour un stage ou un contrat \u00e0 dur\u00e9e (in)d\u00e9termin\u00e9e, trouver un job n\u2019est pas chose ais\u00e9e. Et avant de l\u2019\u00e9pauler lors de son ann\u00e9e d\u2019alternance, vous pouvez \u00e9videmment l\u2019aider \u00e0 trouver ce fameux contrat d\u2019apprentissage ou de professionnalisation.<\/p>\n<p>&nbsp;<\/p>\n<p>Les \u00e9tapes \u00e0 suivre ?<\/p>\n<p>&nbsp;<\/p>\n<p>1\ufe0f\u20e3\u00a0 Il doit d\u2019abord d\u00e9finir dans quel secteur il recherche, quelles entreprises il vise et quel poste il souhaite occuper ;<\/p>\n<p>&nbsp;<\/p>\n<p>2\ufe0f\u20e3 Faire un CV b\u00e9ton et qui correspond \u00e0 ses comp\u00e9tences, ses exp\u00e9riences et \u00e0 ce qu\u2019il cherche ;<\/p>\n<p>&nbsp;<\/p>\n<p>3\ufe0f\u20e3 Une lettre de motivation b\u00e9ton et personnalis\u00e9e ;<\/p>\n<p>&nbsp;<\/p>\n<p>4\ufe0f\u20e3 Se pr\u00e9parer pour les entretiens \u00e0 venir.<\/p>\n\n        <\/div>\n              <\/section>\n\n\n<section class=\"push \">\n        <div >\n            \n                                                <div class=\"push__container  qcd\" data-target=\"_self\" data-qcd=\"aHR0cHM6Ly9zaGVycGFzLmNvbS9mdW5uZWwtc3R1ZGVudC1xdWFsaWZpY2F0aW9u\" data-banner=\"2\" data-name=\"Cours part&amp;rsquo; global #1 = CPG1\" style=\"background-color: #F3FBF7\" >\n                                                                        <div class=\"push__teachers\">\n    <div class=\"d-flex justify-content-center d-md-none\">\n        <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\" alt=\"Logo Sherpas\">\n    <\/div>\n    <div class=\"swiper\">\n        <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Noemie2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">No\u00e9mie<\/p>                          <p class=\"push__teachers-school\">M2 en droit \u00e0 Assas<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Emilie2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Emilie<\/p>                          <p class=\"push__teachers-school\">Sciences Po Lyon<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Jeanne2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Jeanne<\/p>                          <p class=\"push__teachers-school\">Aix-Marseille Universit\u00e9<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">17\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Margot2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Margot<\/p>                          <p class=\"push__teachers-school\">Arts et M\u00e9tiers ParisTech<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">22\u20ac\/h\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Sophie2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Sophie<\/p>                          <p class=\"push__teachers-school\">Sciences Po Bordeaux<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">12\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Fabien2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Fabien<\/p>                          <p class=\"push__teachers-school\">T\u00e9l\u00e9com Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">20\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Emma2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Emma<\/p>                          <p class=\"push__teachers-school\">Dauphine<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">15\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Antoine2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Antoine<\/p>                          <p class=\"push__teachers-school\">Sciences Po Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">18\u20ac\/h\/h<\/p>                     <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                                                    <div class=\"push__content\">\n                                                            <div  class=\"d-none d-md-block\" >\n                                    <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\"\n                                        alt=\"Logo Sherpas\">\n                                <\/div>\n                                                                                        <div class=\"push__title\"><p>Besoin d&rsquo;un <span style=\"color: #48b378;\">prof particulier<\/span> exceptionnel ? \u2728<\/p>\n<\/div>\n                                                                                        <div class=\"push__text\"><p>Nos Sherpas sont l\u00e0 pour aider votre enfant \u00e0 progresser et \u00e0 prendre confiance en lui.<\/p>\n<\/div>\n                                                        <div class=\"push__promo-button   \">\n                                                                                                    <div\n                                        class=\"btn btn-primary\"\n                                        style=\"color: #ffffff; border-color: ; background-color: \"\n\n                                    >\n                                        PRENDRE UN COURS D&rsquo;ESSAI OFFERT\n                                    <\/div>\n                                                            <\/div>\n                                                    <\/div>\n                                    <\/div>\n                                    <\/div>\n    <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"le-soutenir-dans-son-alternance\">Le soutenir dans son alternance \ud83e\udec2<\/h2>\n\n\n\n<p>Votre gosse a enfin trouv\u00e9 son alternance (formation et entreprise), il est temps de l\u2019accompagner durant cette p\u00e9riode si particuli\u00e8re.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"un-soutien-academique-professionnel\">Un soutien acad\u00e9mique &amp; professionnel \ud83e\uddd1\u200d\ud83e\udd1d\u200d\ud83e\uddd1<\/h3>\n\n\n\n<p>Il faut comprendre qu\u2019un alternant est en r\u00e9alit\u00e9 un salari\u00e9 qui jongle entre son travail et les \u00e9tudes. <strong>R\u00e9pondre aux exigences de son entreprise et en m\u00eame temps \u00e0 celles de son \u00e9tablissement scolaire<\/strong> est tr\u00e8s chronophage. \ud83d\udd70\ufe0f<\/p>\n\n\n\n<p>En tant que parent, il faut que vous soyez toujours au fait des progr\u00e8s et\/ou difficult\u00e9s qu\u2019il rencontre \u00e0 l\u2019\u00e9cole ou en entreprise. Aidez votre enfant \u00e0 :&nbsp;<\/p>\n\n\n\n<p><strong>\ud83d\udcc5 Se cr\u00e9er un calendrier \/ emploi du temps<\/strong> rigoureux afin de ne pas \u00eatre sous l\u2019eau ;&nbsp;<\/p>\n\n\n\n<p><strong>\ud83d\udcdd Prioriser ses t\u00e2ches <\/strong>entre les travaux \u00e0 rendre pour l\u2019\u00e9cole et les missions auxquelles il a \u00e9t\u00e9 assign\u00e9 par sa bo\u00eete ;&nbsp;<\/p>\n\n\n\n<p>\ud83e\udd2f <strong>G\u00e9rer les difficult\u00e9s ou les conflits en entreprise<\/strong> : on esp\u00e8re que cela ne sera pas le cas, mais si jamais une telle situation doit arriver, vous \u00eates (professionnellement) exp\u00e9riment\u00e9s et donc \u00e0 m\u00eame de le conseiller ;&nbsp;<\/p>\n\n\n\n<p>etc.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/media.giphy.com\/media\/Fw2PnsOvTu67m\/giphy.gif?cid=ecf05e476hiun2pjh9kot1auimlo8znnrgy2zfopaswhz9y6&amp;ep=v1_gifs_search&amp;rid=giphy.gif&amp;ct=g\" alt=\"Tom et Jerry\" style=\"width:335px;height:auto\"\/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"la-gestion-du-temps-et-du-stress\">La gestion du temps et du stress \u23f3<\/h3>\n\n\n\n<p><strong>Les partiels, le m\u00e9moire de fin d\u2019\u00e9tudes<\/strong>\u2026 Les \u00e9ch\u00e9ances scolaires de milieu et fin d\u2019ann\u00e9e rendent certaines p\u00e9riodes tr\u00e8s charg\u00e9es et difficiles. Valider son dipl\u00f4me tout en ne d\u00e9laissant pas son travail en entreprise n\u2019est pas toujours \u00e9vident. \ud83d\ude25<\/p>\n\n\n\n<p>Voici nos conseils pour apprendre \u00e0 votre enfant <a href=\"https:\/\/sherpas.com\/blog\/comment-gerer-son-temps\/\"><strong>comment g\u00e9rer son temps <\/strong><\/a>! En tant que parent, votre r\u00f4le est crucial, donc assurez-vous de prendre des nouvelles et de le soutenir si besoin. \ud83d\udcde<br><br>Pour ce qui est du stress, soyez attentif et essayez de <a href=\"https:\/\/sherpas.com\/blog\/parents\/a\/signe-stress-ado\/\">rep\u00e9rer les signes<\/a> chez votre enfant. Ce dernier, pour d\u00e9compresser, a sans doute besoin de pratiquer <strong>une activit\u00e9 (sport, musique\u2026) ou d\u2019aller voir un professionnel (psychologue)<\/strong> si le probl\u00e8me persiste. \ud83d\udde3\ufe0f<\/p>\n\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p>Le dispositif <a href=\"https:\/\/sherpas.com\/blog\/parents\/a\/soutien-psy-simplifie-renforce\/\">\u00ab Mon Soutien Psy \u00bb simplifi\u00e9 et renforc\u00e9<\/a> \ud83e\udde0<\/p>\n\n        <\/div>\n    <\/section>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"les-aides-pour-les-alternants\">Les aides pour les alternants \ud83e\ude99<\/h2>\n\n\n\n<p><strong>\ud83d\udcb0 La prime d\u2019activit\u00e9<\/strong> : pour percevoir cette bonification, un alternant doit toucher au 1 082,87 \u20ac net. Le montant de la prime d\u00e9pend du salaire de l\u2019\u00e9tudiant en question et des autres aides qui vous sont d\u00e9j\u00e0 octroy\u00e9es par la Caf.<br><br>Pour ce qui est des d\u00e9marches, vous devez vous rendre sur le site de la Caisse d\u2019Allocations Familiales. Une fois que vous \u00eates au bon endroit, l\u2019alternant doit fournir : carte d\u2019identit\u00e9, RIB et ses trois derniers bulletins de salaire prouvant qu\u2019il est en alternance et combien il per\u00e7oit.&nbsp;<\/p>\n\n\n\n<p>Vous l\u2019aurez compris, votre enfant doit attendre d\u2019avoir effectu\u00e9 trois mois en entreprise avant de pouvoir pr\u00e9tendre \u00e0 cette aide. Rassurez-vous, si son contrat dure un an, la prime d\u2019activit\u00e9 sera bien vers\u00e9e sur douze mois, elle aura simplement un d\u00e9calage de trois mois. D\u2019ailleurs, tous les trimestres, l\u2019alternant ne doit pas oublier de fournir ses trois derniers bulletins de salaire \u00e0 la Caf.<\/p>\n\n\n\n<p><strong>\ud83c\udfe0 Les APL<\/strong> : la Caf, toujours elle, permet aux alternants, entre autres, d\u2019avoir acc\u00e8s \u00e0 une aide personnalis\u00e9e au logement. La somme d\u2019argent per\u00e7ue sur le compte en banque chaque mois d\u00e9pend du loyer et des charges de la personne, de ses revenus, de son statut (\u00e9tudiant) et du type de logement (seul ou en colocation par exemple) dans lequel il se trouve.<\/p>\n\n\n\n<p><strong>\ud83d\udc4d Mobili-Jeune<\/strong> : Action Logement offre entre 10 et 100 \u20ac par mois pour les alternants de moins de 30 ans qui touche moins de 80 % du SMIC.&nbsp;<\/p>\n\n\n\n<p>\ud83d\ude97<strong> L\u2019aide au permis de conduire<\/strong> : cette offre de l&rsquo;\u00c9tat s\u2019adresse seulement aux apprentis (donc en contrat d\u2019apprentissage) et non aux alternants en contrat de professionnalisation. Votre enfant doit :&nbsp;<\/p>\n\n\n\n<p>\u00catre \u00e2g\u00e9 d\u2019au moins 18 ans ;&nbsp;<\/p>\n\n\n\n<p>Avoir un contrat d\u2019apprentissage en cours d\u2019ex\u00e9cution ;&nbsp;<\/p>\n\n\n\n<p>Et \u00eatre engag\u00e9 dans un parcours d\u2019obtention du permis B.<\/p>\n\n\n\n<p>L\u2019aide est de 500 \u20ac forfaitaire, quel que soit le prix du permis en question !&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/media.giphy.com\/media\/UKm1AF0UrCkb6\/giphy.gif?cid=790b7611nybx4q5rhuq8ixjt653nlxyzm8dnj63ty5qyvqnh&amp;ep=v1_gifs_search&amp;rid=giphy.gif&amp;ct=g\" alt=\"Un chien de cartoon qui conduit\" style=\"width:301px;height:auto\"\/><\/figure>\n<\/div>\n\n<section class=\"read-also\">\n    <p class=\"read-also__title\">\u00c0 lire aussi<\/p>\n            <div class=\"read-also__list\">\n            <p><a href=\"https:\/\/sherpas.com\/blog\/parents\/a\/cout-vie-etudiante\/\"> Hausse du co\u00fbt de la vie \u00e9tudiante<\/a> : comment aider financi\u00e8rement votre enfant ? \ud83e\udd11<\/p>\n\n        <\/div>\n    <\/section>\n\n\n<section class=\"push \">\n        <div >\n            \n                                                <div class=\"push__container  qcd\" data-target=\"_self\" data-qcd=\"aHR0cHM6Ly9zaGVycGFzLmNvbS9mdW5uZWwtc3R1ZGVudC1xdWFsaWZpY2F0aW9u\" data-banner=\"2\" data-name=\"Cours part&amp;rsquo; global #2 = CPG2\" style=\"background-color: #F3FBF7\" >\n                                                                        <div class=\"push__teachers\">\n    <div class=\"d-flex justify-content-center d-md-none\">\n        <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\" alt=\"Logo Sherpas\">\n    <\/div>\n    <div class=\"swiper\">\n        <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Clemence2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Cl\u00e9mence<\/p>                          <p class=\"push__teachers-school\">HEC Paris<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">21\u20ac\/h\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Thibault2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Thibault<\/p>                          <p class=\"push__teachers-school\">ENS Paris Ulm<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">20\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Sophie2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Sophie<\/p>                          <p class=\"push__teachers-school\">Sciences Po Bordeaux<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">12\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Noemie2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">No\u00e9mie<\/p>                          <p class=\"push__teachers-school\">M2 en droit \u00e0 Assas<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Fanny2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Fanny<\/p>                          <p class=\"push__teachers-school\">Ponts ParisTech<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">19\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Simon2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Simon<\/p>                          <p class=\"push__teachers-school\">4e ann\u00e9e de m\u00e9decine<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">26\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Nicolas2x.png);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Nicolas<\/p>                          <p class=\"push__teachers-school\">CentraleSup\u00e9lec<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">17\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\">\n                    <div class=\"push__teachers-card\">\n                        <div\n                            class=\"push__teachers-profil\"\n                            \n                            style=\"background-image: url(https:\/\/sherpas.com\/content\/uploads\/sites\/3\/2023\/09\/Victor2x.jpg);\"\n                        >\n                    <\/div>\n                         <p class=\"push__teachers-name\">Victor<\/p>                          <p class=\"push__teachers-school\">ESCP<\/p>                                                     <div class=\"push__teachers-note\">\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                                    <svg  class=\"active\" >\n                                        <use\n                                            xlink:href=\"\/content\/themes\/sherpas-theme\/dist\/images\/sprite.svg#star\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                                                 <p class=\"push__teachers-price\">25\u20ac\/h<\/p>                     <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                                                    <div class=\"push__content\">\n                                                            <div  class=\"d-none d-md-block\" >\n                                    <img decoding=\"async\" class=\"push__logo\" src=\"\/content\/themes\/sherpas-theme\/dist\/images\/logo.svg\"\n                                        alt=\"Logo Sherpas\">\n                                <\/div>\n                                                                                        <div class=\"push__title\"><p>Le premier <span style=\"color: #48b378;\">cours particulier<\/span> est <span style=\"color: #48b378;\">offert !<\/span> \ud83c\udf81<\/p>\n<\/div>\n                                                                                        <div class=\"push__text\"><p>Aidez votre enfant en lui offrant des cours avec un \u00e9tudiant pass\u00e9 par une des meilleures \u00e9coles de France.<\/p>\n<\/div>\n                                                        <div class=\"push__promo-button   \">\n                                                                                                    <div\n                                        class=\"btn btn-primary\"\n                                        style=\"color: ; border-color: ; background-color: \"\n\n                                    >\n                                        J&rsquo;EN PROFITE MAINTENANT\n                                    <\/div>\n                                                            <\/div>\n                                                    <\/div>\n                                    <\/div>\n                                    <\/div>\n    <\/section>\n\n\n\n<p><\/p>\n\n\n\n<p>Notre article est d\u00e9sormais termin\u00e9. On esp\u00e8re que l\u2019alternance de votre prog\u00e9niture se d\u00e9roulera \u00e0 merveille et que vous saurez l\u2019accompagner comme il le faut. \ud83d\udc4f<\/p>\n\n\n\n<p>Et s\u2019il a du mal \u00e0 jongler entre le<em> taf <\/em>et les \u00e9tudes, n\u2019h\u00e9sitez pas \u00e0 lui prendre <a href=\"https:\/\/sherpas.com\/\">des cours de soutien scolaire<\/a> avec l\u2019un de nos professeurs afin qu\u2019il ait un soutien acad\u00e9mique efficace ! \ud83d\ude42<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;268874&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Vous avez aim\u00e9 cet article ?&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Accompagner mon enfant dans son alternance \ud83e\udd1d&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Vous avez aim\u00e9 cet article ?<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;alternance est synonyme de fin d\u2019\u00e9tudes et d&rsquo;insertion professionnelle. En bref, c\u2019est une \u00e9tape cruciale pour chaque jeune (&#8230;)<\/p>\n","protected":false},"author":356,"featured_media":268885,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"category":[9,10],"tag":[],"class_list":["post-268874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-comprendre","category-accompagner"],"acf":[],"_links":{"self":[{"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/posts\/268874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/users\/356"}],"replies":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/comments?post=268874"}],"version-history":[{"count":0,"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/posts\/268874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/media\/268885"}],"wp:attachment":[{"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/media?parent=268874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/category?post=268874"},{"taxonomy":"tag","embeddable":true,"href":"https:\/\/sherpas.com\/blog\/parents\/wp-json\/wp\/v2\/tag?post=268874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}